{"id":279,"date":"2017-01-30T00:16:10","date_gmt":"2017-01-30T02:16:10","guid":{"rendered":"https:\/\/elos360.com.br\/?p=279"},"modified":"2021-07-12T15:31:57","modified_gmt":"2021-07-12T18:31:57","slug":"por-que-o-magazine-luiza-e-um-case-de-sucesso-em-harvard","status":"publish","type":"post","link":"https:\/\/elos360.com.br\/index.php\/2017\/01\/30\/por-que-o-magazine-luiza-e-um-case-de-sucesso-em-harvard\/","title":{"rendered":"Por que o Magazine Luiza \u00e9 um case de sucesso em Harvard?"},"content":{"rendered":"<p style=\"text-align: center;\"><em>Varejista com mais de 22 mil colaboradores e mais de 740 lojas chamou a aten\u00e7\u00e3o da institui\u00e7\u00e3o de forma\u00e7\u00e3o empresarial mais importante do mundo por ter crescido seu faturamento em 415% em 10 anos.<\/em><\/p>\n<p>Todos n\u00f3s gostamos de casos de sucesso sabe por que? Porque eles estimulam a nossa curiosidade e nos trazem altas doses de inspira\u00e7\u00e3o. Quando sabemos que \u00e9 poss\u00edvel conquistar determinada coisa, transformamos nossas pr\u00f3prias cren\u00e7as e nos posicionamos de forma mais positiva diante de grandes transforma\u00e7\u00f5es.<br \/>\nMas afinal, como uma rede de varejo que teve in\u00edcio em Franca, no interior de S\u00e3o Paulo, foi parar na Harvard Business School, a institui\u00e7\u00e3o mais conceituada de forma\u00e7\u00e3o em administra\u00e7\u00e3o do mundo? Veja <a href=\"http:\/\/hbswk.hbs.edu\/item\/how-magazine-luiza-courts-the-poor\" target=\"_blank\" rel=\"noopener noreferrer\"><strong style=\"font-weight: bold;\"><u>AQUI<\/u><\/strong><\/a> o artigo sobre o case no site oficial da institui\u00e7\u00e3o (em ingl\u00eas).<br \/>\nA resposta \u00e9: cultura organizacional. Ou seja, o Magazine Lu\u00edza ganhou essa posi\u00e7\u00e3o de destaque mundial gra\u00e7as a uma s\u00e9rie de valores e princ\u00edpios compartilhados que, quando institu\u00eddos na empresa, orientam o jeito de ser e de se relacionar entre membros da empresa. Sim, membros, porque \u202ah\u00e1 14\u202c anos prestando servi\u00e7os para essa empresa, posso lhe dizer que ela \u00e9 uma empresa viva e tem algo que gosto de chamar de alma. \u202c\u202c<br \/>\nAssim como um ser humano, a empresa tamb\u00e9m n\u00e3o \u00e9 perfeita e seus membros cometem erros, e at\u00e9 a\u00ed, n\u00e3o h\u00e1 nenhum problema. Seus acertos s\u00e3o maiores e percebidos de fora, e seu principal diferencial, percebido por dentro. \u00c9 inspirador ver a busca pelo certo e pelo novo, a ousadia de fazer diferente, o est\u00edmulo pelo olho no olho, pela verdade e transpar\u00eancia, assim como a valoriza\u00e7\u00e3o das pessoas, o construir junto, a celebra\u00e7\u00e3o de conquistas e reconhecimento dos destaques. A lista de valores essenciais continua. E quem n\u00e3o gostaria de trabalhar em uma empresa que estimula o melhor de cada um e a busca o ganha-ganha?<br \/>\n<strong style=\"font-weight: bold;\">Mas, como \u00e9 a cultura organizacional do Magazine Lu\u00edza?<\/strong><br \/>\nCultura se faz de cima para baixo atrav\u00e9s do \u201cc\u00e9rebro-gestor\u201d, o empreendedor, o propriet\u00e1rio ou o CEO (chefe). Neste caso, essa hist\u00f3ria bacana come\u00e7ou l\u00e1 atr\u00e1s com a mente de uma grande l\u00edder, a Luiza Helena, assim que assumiu a empresa de sua tia, D. Luiza.<br \/>\nNuma \u00e9poca departamentalizada, onde cada um ficava no seu quadrado fazendo as tarefas que lhes eram atribu\u00eddas, Luiza quebrou paredes e horizontalizou rela\u00e7\u00f5es, criando uma pol\u00edtica de portas abertas com simplicidade, abertura ao di\u00e1logo e foco no fazer acontecer.<br \/>\nA pr\u00e1tica sempre esteve a frente da teoria e a \u00e9tica a frente dos resultados. Quantas vezes presenciei o direcionamento para falar a verdade ao cliente, n\u00e3o embutir servi\u00e7os e buscar um lucro saud\u00e1vel.<br \/>\nNestes \u00faltimos anos, foi levantada uma bandeira dos inegoci\u00e1veis &#8211; uma forma de n\u00e3o abrir m\u00e3o dos princ\u00edpios que buscam o bem comum e um crescimento com alma. A cultura, no caso do Magazine Lu\u00edza, come\u00e7ou de dentro, inspirada pela personalidade da Luiza e foi, aos poucos, sendo institucionalizada de forma org\u00e2nica e transparente.<\/p>\n<p style=\"text-align: center;\"><em>Lu\u00edza Helena<\/em><\/p>\n<p><strong style=\"font-weight: bold;\">Como \u00e9 por dentro do Magazine Lu\u00edza?<\/strong><br \/>\nL\u00e1 n\u00e3o se v\u00ea placas de miss\u00e3o, vis\u00e3o e valores na parede &#8211; t\u00e3o comum em empresas comuns. Frases como o hino da empresa e do Credo ilustram fragmentos da \u201calma\u201d da empresa, foi repassada com comunica\u00e7\u00e3o interna e exemplos. Falando nisso, e, sabendo do quanto l\u00edderes s\u00e3o guardi\u00f5es multiplicadores da cultura, investimentos no desenvolvimento e amplia\u00e7\u00e3o de consci\u00eancia s\u00e3o feitos periodicamente, assim como rtabalhos de fortalecimento de cultura e clima \u2013 preventivo e interventivo.<br \/>\nO valor pela colabora\u00e7\u00e3o e democracia criou o conselho de colaboradores e a regra de ouro ficou registrada atr\u00e1s dos crach\u00e1s, e lembra as pessoas para fazerem aos outros o que gostariam que fizessem a elas pr\u00f3prias.<br \/>\nSei que na teoria tudo parece f\u00e1cil, mas \u00e9 impressionante como a pr\u00e1tica, cada vez mais, tem provado que vale a pena investir em valores e princ\u00edpios essenciais, n\u00e3o s\u00f3 por se tornar modelo mundial e exemplo na Harvard Business School, mas porque d\u00e1 resultados \u2013 quantitativos e qualitativos e \u00e9 bom para todos!<br \/>\nAl\u00e9m de estar sempre a frente da cultura organizacional, Luiza Helena gosta de passar o conhecimento \u00e0 frente e est\u00e1 disposta a compartilhar com seus colaboradores e parceiros o que aprende e descobre. Quem j\u00e1 trabalhou l\u00e1 deve se lembrar das fitas cassetes e dos encontr\u00f5es memor\u00e1veis. Hoje, com o passer do tempo e com o avan\u00e7o da tecnologia, vieram as tvs e as r\u00e1dios corporativas, um r\u00e1pido crescimento, uma abertura de capital e novas estrat\u00e9gias.<br \/>\nAtualmente, a cultura do Magazine Luiza est\u00e1 nas m\u00e3os do novo presidente: o filho da Luiza Helena, Frederico. O desafio de gerir uma grande empresa varejista com mais de 22 mil colaboradores e 700 lojas, torna-se tamb\u00e9m a promessa de manter a ess\u00eancia dessa cultura de princ\u00edpios que, na verdade, n\u00e3o \u00e9 personalizada ou exclusiva da Luiza Helena, mas pertencente a todos os profissionais que se sentem parte de um Todo, se orientam por \u00e9tica e empatia e buscam o bem comum dentro e fora do seu ambiente de trabalho.<br \/>\n<strong style=\"font-weight: bold;\">O desafio da cultura de princ\u00edpios na era digital<\/strong><br \/>\nNa cultura de princ\u00edpios os l\u00edderes e colaboradores t\u00eam a certeza de que a verdade liberta e que a integridade junto com a transpar\u00eancia constr\u00f3em rela\u00e7\u00f5es de confian\u00e7a. Uma cultura de princ\u00edpios ajuda a fortalecer a alma da empresa, faz cada um se sentir parte de uma grande fam\u00edlia e incentiva todos a dar o seu melhor.<br \/>\n\u00c9 neste ambiente que Frederico agora tem o desafio de manter as ra\u00edzes com um novo posicionamento digital, que faz o mesmo convite \u201cvem ser feliz\u201d, mas de forma diferente. Dessa vez, a empresa convida \u00e0 ser feliz de v\u00e1rias formas, em m\u00faltiplos canais e plataformas.<br \/>\nO trabalho de crescer digital e com alma \u00e9 \u00e1rduo e continuo e o primeiro cliente \u00e9 o interno &#8211; o colaborador. No meu ponto de vista, as estrat\u00e9gias adotadas nesta era digital est\u00e3o sendo bem sucedidas e o desafio do Fred (assim chamado) foi aceito por suas lideran\u00e7as e colaboradores. N\u00e3o \u00e9 a toa que a empresa \u00e9, ainda, uma das melhores para se trabalhar no Brasil. Espero e contribuo, assim como os demais, para que seja assim por muito tempo!<\/p>\n<div class=\"clearfix\"><\/div>","protected":false},"excerpt":{"rendered":"<p>Varejista com mais de 22 mil colaboradores e mais de 740 lojas chamou a aten\u00e7\u00e3o&#8230;<\/p>\n","protected":false},"author":2,"featured_media":280,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[33],"tags":[],"class_list":["post-279","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cultura-organizacional"],"_links":{"self":[{"href":"https:\/\/elos360.com.br\/index.php\/wp-json\/wp\/v2\/posts\/279","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elos360.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elos360.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elos360.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/elos360.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=279"}],"version-history":[{"count":1,"href":"https:\/\/elos360.com.br\/index.php\/wp-json\/wp\/v2\/posts\/279\/revisions"}],"predecessor-version":[{"id":8578,"href":"https:\/\/elos360.com.br\/index.php\/wp-json\/wp\/v2\/posts\/279\/revisions\/8578"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elos360.com.br\/index.php\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/elos360.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=279"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elos360.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=279"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elos360.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=279"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}